{"id":4876,"date":"2025-08-14T17:31:38","date_gmt":"2025-08-14T09:31:38","guid":{"rendered":"https:\/\/dunwellgroup.net\/?page_id=4876"},"modified":"2025-08-15T09:55:56","modified_gmt":"2025-08-15T01:55:56","slug":"biologic-sr2-pet","status":"publish","type":"page","link":"https:\/\/dunwellgroup.net\/zh\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/","title":{"rendered":"BIOLOGIC\u00ae \u5bf5\u5967\u6a02 SR2"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4876\" class=\"elementor elementor-4876\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40028aa e-grid e-con-boxed e-con e-parent\" data-id=\"40028aa\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_blur_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7,&quot;sizes&quot;:[]},&quot;background_motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\" data-e-bg-lazyload=\"\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-abb34e0 e-con-full e-flex e-con e-child\" data-id=\"abb34e0\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-34c4ddb e-con-full e-flex e-con e-child\" data-id=\"34c4ddb\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1cccf90 elementor-widget elementor-widget-heading\" data-id=\"1cccf90\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dunwellgroup.net\/zh\/environmental-solutions\/\">ENVIRONMENTAL SOLUTIONS \/ <\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41e808d elementor-widget elementor-widget-heading\" data-id=\"41e808d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dunwellgroup.net\/zh\/environmental-solutions\/green-products-services\/\">GREEN PRODUCTS & SERVICES \/<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7901b3 elementor-widget elementor-widget-text-editor\" data-id=\"c7901b3\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tA proprietary plant-based blend of organic micronutrients that stimulates specific aerobic, anaerobic, and facultative bacteria species.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2b9455 e-flex e-con-boxed e-con e-parent\" data-id=\"e2b9455\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0c00813 e-con-full e-flex e-con e-child\" data-id=\"0c00813\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4cfa4d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b4cfa4d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Biologic\u2122 SR2 Pet Odor Control Spray \u2013 Safe &amp; Effective Odor Elimination<\/p><p>SR2 is an advanced spray that permanently destroys pet odors at the molecular level, unlike fragranced products that only mask smells. Its science-backed formula tackles urine, feces, and vomit odors while being gentle for homes with pets.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-350894d elementor-widget elementor-widget-image\" data-id=\"350894d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"228\" height=\"300\" src=\"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2024\/06\/4-228x300-1.jpg\" class=\"attachment-medium size-medium wp-image-1372\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e53834 elementor-widget elementor-widget-image\" data-id=\"1e53834\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"208\" src=\"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2025\/03\/ISO-CAN2369-grey-01-300x208.png\" class=\"attachment-medium size-medium wp-image-4306\" alt=\"\" srcset=\"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2025\/03\/ISO-CAN2369-grey-01-300x208.png 300w, https:\/\/dunwellgroup.net\/wp-content\/uploads\/2025\/03\/ISO-CAN2369-grey-01-1024x711.png 1024w, https:\/\/dunwellgroup.net\/wp-content\/uploads\/2025\/03\/ISO-CAN2369-grey-01-768x534.png 768w, https:\/\/dunwellgroup.net\/wp-content\/uploads\/2025\/03\/ISO-CAN2369-grey-01-1536x1067.png 1536w, https:\/\/dunwellgroup.net\/wp-content\/uploads\/2025\/03\/ISO-CAN2369-grey-01-2048x1423.png 2048w, https:\/\/dunwellgroup.net\/wp-content\/uploads\/2025\/03\/ISO-CAN2369-grey-01-18x12.png 18w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3ccfc9 elementor-widget elementor-widget-heading\" data-id=\"e3ccfc9\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why Pet Owners Choose SR2<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-300d762 elementor-widget elementor-widget-text-editor\" data-id=\"300d762\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul>\n<li>Eliminates Odors \u2013 Breaks down ammonia (Urine), H2S (feces) and organic compounds (vomit or sweat).<\/li>\n<li>Pet-Safe \u2013 Plant-based, all natural, non-toxic and non-irritating.<\/li>\n<li>Prevents Re-Marking \u2013 Removes scent triggers pets use to re-soil areas.<\/li>\n<li>Multi-Surface Use \u2013 Safe for carpets, bedding, crates, and litter boxes.<br>(&#8220;To protect delicate surfaces, we recommend testing in an inconspicuous area first and avoid over-application.&nbsp; In case of over-spraying, wipe dry with a clean cloth immediately)<\/li>\n<\/ul>\n<div>\n<div>&nbsp;<\/div>\n<div>Perfect for stubborn pet smells, SR2 works without harsh chemicals\u2014leaving your home truly fresh and odor free.<\/div><div><br><\/div>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55ab851 elementor-widget elementor-widget-heading\" data-id=\"55ab851\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">International Testing Certifications<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37c5559 elementor-widget__width-initial elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"37c5559\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-bc15b5d swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-b951b06 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-7317eee swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-b534ebb swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-034b022 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-399f0b1 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-05e7467 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-d253f12 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Click Here<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous slide<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next slide<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f54a93 e-flex e-con-boxed e-con e-parent\" data-id=\"8f54a93\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d95616 elementor-widget elementor-widget-text-editor\" data-id=\"8d95616\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>*BIOLOGIC and SciCorp are trademarks of SciCorp International Corp.<\/p><p>Manufacturer\u2019s address: 13-3300 Ridgeway Drive, Mississauga, L5L5Z9, ON, Canada<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ENVIRONMENTAL SOLUTIONS \/ GREEN PRODUCTS &#038; SERVICES \/ Biologic\u2122 SR2 Pet Odor Control Spray \u2013 Safe &amp; Effective Odor Elimination SR2 is an advanced spray that permanently destroys pet odors at the molecular level, unlike fragranced products that only mask smells. Its science-backed formula tackles urine, feces, and vomit odors while being gentle for homes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1414,"parent":960,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BIOLOGIC\u00ae SR2 Pet - Dunwell Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dunwellgroup.net\/zh\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/\" \/>\n<meta property=\"og:locale\" content=\"zh_HK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BIOLOGIC\u00ae SR2 Pet - Dunwell Group\" \/>\n<meta property=\"og:description\" content=\"ENVIRONMENTAL SOLUTIONS \/ GREEN PRODUCTS &#038; SERVICES \/ Biologic\u2122 SR2 Pet Odor Control Spray \u2013 Safe &amp; Effective Odor Elimination SR2 is an advanced spray that permanently destroys pet odors at the molecular level, unlike fragranced products that only mask smells. Its science-backed formula tackles urine, feces, and vomit odors while being gentle for homes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dunwellgroup.net\/zh\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/\" \/>\n<meta property=\"og:site_name\" content=\"Dunwell Group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dunwellhk\/?locale=zh_HK\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T01:55:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2024\/06\/SciCorp-logo-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9810\u8a08\u95b1\u8b80\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 \u5206\u9418\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/\",\"url\":\"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/\",\"name\":\"BIOLOGIC\u00ae SR2 Pet - Dunwell Group\",\"isPartOf\":{\"@id\":\"https:\/\/dunwellgroup.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2024\/06\/SciCorp-logo-scaled-1.jpg\",\"datePublished\":\"2025-08-14T09:31:38+00:00\",\"dateModified\":\"2025-08-15T01:55:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/#breadcrumb\"},\"inLanguage\":\"zh-HK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-HK\",\"@id\":\"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/#primaryimage\",\"url\":\"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2024\/06\/SciCorp-logo-scaled-1.jpg\",\"contentUrl\":\"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2024\/06\/SciCorp-logo-scaled-1.jpg\",\"width\":2560,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dunwellgroup.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Environmental Solutions\",\"item\":\"https:\/\/dunwellgroup.net\/environmental-solutions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Green Products &#038; Services\",\"item\":\"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"BIOLOGIC\u00ae SR2 Pet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dunwellgroup.net\/#website\",\"url\":\"https:\/\/dunwellgroup.net\/\",\"name\":\"Dunwell Group\",\"description\":\"Leaders in Enviromental Technology\",\"publisher\":{\"@id\":\"https:\/\/dunwellgroup.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dunwellgroup.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-HK\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dunwellgroup.net\/#organization\",\"name\":\"Dunwell Group\",\"url\":\"https:\/\/dunwellgroup.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-HK\",\"@id\":\"https:\/\/dunwellgroup.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/172.31.10.242\/wp-content\/uploads\/2024\/03\/logo-primary.png\",\"contentUrl\":\"https:\/\/172.31.10.242\/wp-content\/uploads\/2024\/03\/logo-primary.png\",\"width\":1114,\"height\":251,\"caption\":\"Dunwell Group\"},\"image\":{\"@id\":\"https:\/\/dunwellgroup.net\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dunwellhk\/?locale=zh_HK\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BIOLOGIC\u00ae SR2 Pet - Dunwell Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dunwellgroup.net\/zh\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/","og_locale":"zh_HK","og_type":"article","og_title":"BIOLOGIC\u00ae SR2 Pet - Dunwell Group","og_description":"ENVIRONMENTAL SOLUTIONS \/ GREEN PRODUCTS &#038; SERVICES \/ Biologic\u2122 SR2 Pet Odor Control Spray \u2013 Safe &amp; Effective Odor Elimination SR2 is an advanced spray that permanently destroys pet odors at the molecular level, unlike fragranced products that only mask smells. Its science-backed formula tackles urine, feces, and vomit odors while being gentle for homes [&hellip;]","og_url":"https:\/\/dunwellgroup.net\/zh\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/","og_site_name":"Dunwell Group","article_publisher":"https:\/\/www.facebook.com\/dunwellhk\/?locale=zh_HK","article_modified_time":"2025-08-15T01:55:56+00:00","og_image":[{"width":2560,"height":1240,"url":"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2024\/06\/SciCorp-logo-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u9810\u8a08\u95b1\u8b80\u6642\u9593":"2 \u5206\u9418"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/","url":"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/","name":"BIOLOGIC\u00ae SR2 Pet - Dunwell Group","isPartOf":{"@id":"https:\/\/dunwellgroup.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/#primaryimage"},"image":{"@id":"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/#primaryimage"},"thumbnailUrl":"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2024\/06\/SciCorp-logo-scaled-1.jpg","datePublished":"2025-08-14T09:31:38+00:00","dateModified":"2025-08-15T01:55:56+00:00","breadcrumb":{"@id":"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/#breadcrumb"},"inLanguage":"zh-HK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/"]}]},{"@type":"ImageObject","inLanguage":"zh-HK","@id":"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/#primaryimage","url":"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2024\/06\/SciCorp-logo-scaled-1.jpg","contentUrl":"https:\/\/dunwellgroup.net\/wp-content\/uploads\/2024\/06\/SciCorp-logo-scaled-1.jpg","width":2560,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/biologic-sr2-pet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dunwellgroup.net\/"},{"@type":"ListItem","position":2,"name":"Environmental Solutions","item":"https:\/\/dunwellgroup.net\/environmental-solutions\/"},{"@type":"ListItem","position":3,"name":"Green Products &#038; Services","item":"https:\/\/dunwellgroup.net\/environmental-solutions\/green-products-services\/"},{"@type":"ListItem","position":4,"name":"BIOLOGIC\u00ae SR2 Pet"}]},{"@type":"WebSite","@id":"https:\/\/dunwellgroup.net\/#website","url":"https:\/\/dunwellgroup.net\/","name":"Dunwell Group","description":"Leaders in Enviromental Technology","publisher":{"@id":"https:\/\/dunwellgroup.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dunwellgroup.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-HK"},{"@type":"Organization","@id":"https:\/\/dunwellgroup.net\/#organization","name":"Dunwell Group","url":"https:\/\/dunwellgroup.net\/","logo":{"@type":"ImageObject","inLanguage":"zh-HK","@id":"https:\/\/dunwellgroup.net\/#\/schema\/logo\/image\/","url":"https:\/\/172.31.10.242\/wp-content\/uploads\/2024\/03\/logo-primary.png","contentUrl":"https:\/\/172.31.10.242\/wp-content\/uploads\/2024\/03\/logo-primary.png","width":1114,"height":251,"caption":"Dunwell Group"},"image":{"@id":"https:\/\/dunwellgroup.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dunwellhk\/?locale=zh_HK"]}]}},"_links":{"self":[{"href":"https:\/\/dunwellgroup.net\/zh\/wp-json\/wp\/v2\/pages\/4876"}],"collection":[{"href":"https:\/\/dunwellgroup.net\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dunwellgroup.net\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dunwellgroup.net\/zh\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dunwellgroup.net\/zh\/wp-json\/wp\/v2\/comments?post=4876"}],"version-history":[{"count":15,"href":"https:\/\/dunwellgroup.net\/zh\/wp-json\/wp\/v2\/pages\/4876\/revisions"}],"predecessor-version":[{"id":4896,"href":"https:\/\/dunwellgroup.net\/zh\/wp-json\/wp\/v2\/pages\/4876\/revisions\/4896"}],"up":[{"embeddable":true,"href":"https:\/\/dunwellgroup.net\/zh\/wp-json\/wp\/v2\/pages\/960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dunwellgroup.net\/zh\/wp-json\/wp\/v2\/media\/1414"}],"wp:attachment":[{"href":"https:\/\/dunwellgroup.net\/zh\/wp-json\/wp\/v2\/media?parent=4876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}